{"id":263,"date":"2015-12-03T00:11:10","date_gmt":"2015-12-02T23:11:10","guid":{"rendered":"http:\/\/www.inforender.it\/wordpress\/?p=263"},"modified":"2019-02-13T22:01:59","modified_gmt":"2019-02-13T21:01:59","slug":"calcolo-dilatazione-termica","status":"publish","type":"post","link":"https:\/\/www.inforender.it\/wordpress\/calcolo-dilatazione-termica\/","title":{"rendered":"Calcolo dilatazione termica LINEARE e VOLUMETRICA"},"content":{"rendered":"<p>Calcolo dilatazione termica<\/p>\n<h2>Calcolo dilatazione termica<\/h2>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.dropbox.com\/s\/wm1l4ry1j57h85e\/DILATAZIONE%20TERMICA.xlsx?dl=0\">PUOI SCARICARE QUI IL FOGLIO EXCEL PER CALCOLARE LA DILATAZIONE TERMICA LINEARE E VOLUMETRICA<\/a><\/p>\n<blockquote><p>La <b>dilatazione termica<\/b> \u00e8 il fenomeno fisico che si realizza quando in un corpo (liquido, gassoso o solido) si verifica un aumento di volume all&#8217;aumentare della temperatura.<\/p>\n<p>A livello atomico, si spiega con la variazione dell&#8217;oscillazione degli atomi attorno ad un punto di equilibrio, che normalmente viene identificato con la lunghezza di legame. In realt\u00e0 l&#8217;oscillazione non \u00e8 simmetrica, ma \u00e8 maggiore nel senso dell&#8217;allontanamento dal punto di equilibrio. A livello microscopico ci\u00f2 si traduce in un aumento del volume del materiale con l&#8217;aumento della temperatura.<\/p>\n<p>Come si deduce dal nome, il materiale si dilata in risposta all&#8217;aumento di temperatura. Nel caso l&#8217;andamento di tale dilatazione in funzione della variazione di temperatura sia lineare (come \u00e8 per la maggior parte dei materiali per piccole variazioni &#8211; vedi sviluppo in serie di Taylor) resta definito il coefficiente di dilatazione termica. Nei corpi solidi, avvengono tre tipi di dilatazione: dilatazione cubica, dilatazione superficiale e dilatazione lineare.<\/p>\n<p>Wikipedia<\/p><\/blockquote>\n<p>La definizione di wikipedia \u00e8 una buona rappresentazione del fenomeno fisico che sta dietro il calcolo della dilatazione termica. In ingegneria conoscere bene queste formule e poterle applicare con facilit\u00e0 pu\u00f2 essere utile in molti casi pratici. In edilizia, a dir la verit\u00e0, \u00e8 poco utilizzata, in quanto le variazioni di dimensione derivanti dal un\u00a0\u0394T si applicano ad elementi &#8220;corti&#8221;, invece strutture con elementi &#8220;lunghi&#8221;, ad esempio nelle travi da ponte, possono nascere delle coazioni derivanti appunto dalle dilatazioni termiche, che vanno valutate in sede progettuale.<\/p>\n<p>Un&#8217;altra breve considerazione sull&#8217;influenza delle dilatazioni termiche hanno sulle opere civili, riguarda l&#8217;accostamento di materiali diversi. Accostare materiali con un coefficiente di dilatazione simile, porta a degli innegabili vantaggi, e in genere si cerca di fare questo, prendiamo ad esempio il cls e l&#8217;acciaio, sono stati accoppiati per formare il cemento armato, anche perch\u00e8 hanno, appunto, un comportamento molto simile se soggette ad una differenza di temperatura.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.dropbox.com\/s\/wm1l4ry1j57h85e\/DILATAZIONE%20TERMICA.xlsx?dl=0\">PUOI SCARICARE QUI IL FOGLIO EXCEL PER CALCOLARE LA DILATAZIONE TERMICA LINEARE E VOLUMETRICA<\/a><\/p>\n<h3>Calcolo dilatazione termica monoassiale<\/h3>\n<p style=\"text-align: center;\">\u0394T x L0 x\u00a0\u03b1 =\u00a0\u0394L<\/p>\n<p style=\"text-align: left;\">Dove:<\/p>\n<p style=\"text-align: left;\">\u0394T= differenza di temperatura (T-T0)<\/p>\n<p style=\"text-align: left;\">L0= lunghezza iniziale<\/p>\n<p style=\"text-align: left;\">\u03b1 =\u00a0\u00e8 il coefficiente di dilatazione lineare (e si misura in K<sup>\u22121<\/sup>).<\/p>\n<p style=\"text-align: left;\">\u0394L= dilatazione termica lineare<\/p>\n<p style=\"text-align: left;\">La lunghezza finale si trova aggiungendo a quella iniziale &#8220;L0&#8221;\u00a0la dilatazione avvenuta\u00a0\u0394L.<\/p>\n<h3>Calcolo dilatazione termica\u00a0volumetrica<\/h3>\n<p style=\"text-align: center;\">\u0394T x V0 x k =\u00a0\u0394V<\/p>\n<p style=\"text-align: left;\">Dove:<\/p>\n<p style=\"text-align: left;\">\u0394T=differenza di temperatura (T-T0)<\/p>\n<p style=\"text-align: left;\">V0= volume iniziale<\/p>\n<p style=\"text-align: left;\">k=\u00a0\u00e8 il coefficiente di dilatazione cubica. Esso esprime l&#8217;aumento volumetrico di un corpo, avente un volume iniziale unitario di 1 m\u00b3, quando la sua temperatura aumenta di 1\u00a0\u00b0C.<\/p>\n<p style=\"text-align: left;\">\u0394V=dilatazione termica volumetrica<\/p>\n<p style=\"text-align: left;\">Il\u00a0volume finale si trova aggiungendo a quello iniziale\u00a0&#8220;V0&#8221;\u00a0la dilatazione avvenuta\u00a0\u0394V.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.dropbox.com\/s\/wm1l4ry1j57h85e\/DILATAZIONE%20TERMICA.xlsx?dl=0\">PUOI SCARICARE QUI IL FOGLIO EXCEL PER CALCOLARE LA DILATAZIONE TERMICA LINEARE E VOLUMETRICA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calcolo dilatazione termica Calcolo dilatazione termica PUOI SCARICARE QUI IL FOGLIO EXCEL PER CALCOLARE LA DILATAZIONE TERMICA LINEARE E VOLUMETRICA La dilatazione termica \u00e8 il fenomeno fisico che si realizza quando in un corpo (liquido,<\/p>\n","protected":false},"author":1,"featured_media":265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[29,44,27,43],"tags":[46,47,40,48,49,50,45,34],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/www.inforender.it\/wordpress\/wp-content\/uploads\/2015\/12\/Dilatazione-Termica.jpg?fit=3840%2C1200&ssl=1","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paIhoZ-4f","_links":{"self":[{"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/posts\/263"}],"collection":[{"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":5,"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"predecessor-version":[{"id":330,"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/posts\/263\/revisions\/330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/media\/265"}],"wp:attachment":[{"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inforender.it\/wordpress\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}